{"id":1933,"date":"2016-03-03T20:19:37","date_gmt":"2016-03-03T20:19:37","guid":{"rendered":"http:\/\/www.emco.mil.cl\/?p=1933"},"modified":"2021-09-29T09:34:18","modified_gmt":"2021-09-29T12:34:18","slug":"jefe-del-estado-mayor-conjunto-recibe-visita-del-embajador-de-los-ee-uu","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2016\/03\/03\/jefe-del-estado-mayor-conjunto-recibe-visita-del-embajador-de-los-ee-uu\/","title":{"rendered":"Jefe del Estado Mayor Conjunto recibe visita del Embajador de los EE.UU."},"content":{"rendered":"<p>Una visita protocolar realiz\u00f3 la tarde de hoy el Excelent\u00edsimo Embajador de los Estados Unidos de Norteam\u00e9rica en Chile, Michael A. Hammer, al Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino Nu\u00f1ez.<\/p>\n<p>El embajador Hammer es funcionario de carrera del Servicio Exterior de los Estados Unidos desde 1988, habiendo cumplido destinaciones tambi\u00e9n en Bolivia, Noruega, Islandia y Dinamarca. Previo a su nombramiento, se desempe\u00f1\u00f3 como Secretario de Estado Adjunto de EE.UU. para Asuntos P\u00fablicos en el Departamento de Estado, donde dirigi\u00f3 temas de comunicaciones y prensa; asimismo, entre los a\u00f1os 2009 y 2011, fue Asesor Especial del Presidente Obama, Director de Prensa y Comunicaciones, y Portavoz del Consejo de Seguridad Nacional. Previamente, trabaj\u00f3 en la Casa Blanca como Vice-Portavoz del Consejo de Seguridad Nacional, entre 1999 y 2000, y como Director de Asuntos Andinos, entre 2000 y 2001.<\/p>\n<p>El Presidente Obama nomin\u00f3 a Michael Hammer como embajador de los Estados Unidos en Chile el 24 de junio de 2013, siendo confirmado en su cargo por el Senado de los EE.UU., en marzo de 2014.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una visita protocolar realiz\u00f3 la tarde de hoy el Excelent\u00edsimo Embajador de los Estados Unidos de Norteam\u00e9rica en Chile, Michael A. Hammer, al Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Arturo Merino Nu\u00f1ez. El embajador Hammer es funcionario de carrera del Servicio Exterior de los Estados Unidos desde 1988, habiendo cumplido destinaciones tambi\u00e9n en&#8230;<\/p>\n","protected":false},"author":6,"featured_media":5823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-1933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1933"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1933\/revisions"}],"predecessor-version":[{"id":6552,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1933\/revisions\/6552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/5823"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}