{"id":1730,"date":"2021-04-13T16:31:00","date_gmt":"2021-04-13T20:31:00","guid":{"rendered":"http:\/\/10.195.30.25\/?p=1730"},"modified":"2021-09-27T15:46:25","modified_gmt":"2021-09-27T18:46:25","slug":"conversatorio-sobre-nueva-politica-nacional-para-la-reduccion-del-riesgo-de-desastres","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2021\/04\/13\/conversatorio-sobre-nueva-politica-nacional-para-la-reduccion-del-riesgo-de-desastres\/","title":{"rendered":"Conversatorio sobre Nueva Pol\u00edtica Nacional para la Reducci\u00f3n del Riesgo de Desastres"},"content":{"rendered":"\n<figure class=\"wp-block-image is-style-default\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/EMCO20210409-005.jpg\" alt=\"EMCO20210409-005\"\/><\/figure>\n\n\n\n<p>El d\u00eda viernes 09 de abril de 2021, La Oficina Nacional de Emergencia del Ministerio del Interior y Seguridad P\u00fablica, encabezada por el Subdirector Nacional, Sr. Crist\u00f3bal Mena, realiz\u00f3 la primera reuni\u00f3n plenaria de la Plataforma Nacional para la Reducci\u00f3n del Riesgo de Desastres (RRD), la cual tuvo como objeto materializar un conversatorio referente a la \u201cNueva Pol\u00edtica Nacional para la Reducci\u00f3n del Riesgo de Desastres: Desaf\u00edos para un Chile resiliente y sostenible\u201d.<\/p>\n\n\n\n<p>Esta actividad se realiz\u00f3 en modalidad On-line y cont\u00f3 con una concurrida y activa participaci\u00f3n de los diferentes integrantes del Sistema Nacional de Protecci\u00f3n Civil, del cual es parte el Estado Mayor Conjunto, siendo representado en esta ocasi\u00f3n por el Contraalmirante Jos\u00e9 Luis Fern\u00e1ndez Morales, Director de Operaciones y Conducci\u00f3n Conjunta, acompa\u00f1ado por el Coronel Marcelo Montesinos De Ugarte, Jefe del Departamento III \u201cConducci\u00f3n Militar en Desastres\u201d.<\/p>\n\n\n\n<p>El conversatorio fue enfocado en la presentaci\u00f3n de la Nueva Pol\u00edtica Nacional de RRD, la cual fue aprobada mediante DS 434 del Ministerio del Interior y Seguridad P\u00fablica y recientemente publicada en el Diario Oficial con fecha 16 de marzo de 2021, mediante la cual se establecen para los pr\u00f3ximos 10 a\u00f1os, las directrices para fortalecer la Gesti\u00f3n del Riesgo de Desastres que es impulsada y coordinada por el Estado de Chile.<\/p>\n\n\n\n<p>Cabe mencionar que, para la obtenci\u00f3n de esta nueva Pol\u00edtica de RRD, el EMCO trabaj\u00f3 el aporte del sector Defensa en conjunto con los integrantes del Sistema Nacional de protecci\u00f3n civil, liderados por ONEMI.<\/p>\n\n\n\n<p>Durante el conversatorio expusieron representantes del Sistema Nacional de Protecci\u00f3n Civil y tambi\u00e9n se analizaron los 05 ejes prioritarios de la Nueva Pol\u00edtica, tales como: Comprender el Riesgo de Desastres; Fortalecer la Gobernanza de la Gesti\u00f3n del Riesgo de Desastres; Planificar e Invertir en la Reducci\u00f3n del Riesgo de Desastres para la Resiliencia; Proporcionar una Respuesta Eficiente y Eficaz; Fomentar una recuperaci\u00f3n Sostenible.<\/p>\n\n\n\n<p>Para el Estado Mayor Conjunto y dentro de su \u00e1rea de misi\u00f3n \u201cEmergencia Nacional y Protecci\u00f3n Civil\u201d es de vital importancia mantenerse actualizado los lineamientos que dicta esta pol\u00edtica, que son las orientaciones que debe trabajar y ser parte activa dentro de los ciclos de la Gesti\u00f3n del Riesgo de Desastres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda viernes 09 de abril de 2021, La Oficina Nacional de Emergencia del Ministerio del Interior y Seguridad P\u00fablica, encabezada por el Subdirector Nacional, Sr. Crist\u00f3bal Mena, realiz\u00f3 la primera reuni\u00f3n plenaria de la Plataforma Nacional para la Reducci\u00f3n del Riesgo de Desastres (RRD), la cual tuvo como objeto materializar un conversatorio referente a&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[12,3],"tags":[],"class_list":["post-1730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1730"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1730\/revisions"}],"predecessor-version":[{"id":1731,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1730\/revisions\/1731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/1802"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}