{"id":1714,"date":"2021-05-26T16:10:00","date_gmt":"2021-05-26T20:10:00","guid":{"rendered":"http:\/\/10.195.30.25\/?p=1714"},"modified":"2021-09-27T15:46:00","modified_gmt":"2021-09-27T18:46:00","slug":"estado-mayor-conjunto-participa-en-intercambio-de-experiencias-de-apoyo-militar-en-emergencias-y-desastres-all-hazard","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2021\/05\/26\/estado-mayor-conjunto-participa-en-intercambio-de-experiencias-de-apoyo-militar-en-emergencias-y-desastres-all-hazard\/","title":{"rendered":"Estado Mayor Conjunto participa en intercambio de experiencias de apoyo militar en emergencias y desastres \u201cAll Hazard\u201d"},"content":{"rendered":"\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/EMCO20210525-004-485x330.jpg\" alt=\"EMCO20210525-004\"\/><\/figure><\/div>\n\n\n\n<p>Este martes 25 de mayo, el Estado Mayor Conjunto particip\u00f3 en un intercambio de experiencias con el Departamento Militar del Estado de Texas (TMD) de los Estados Unidos, consistente en un simulacro de ensayos de conceptos operacionales denominado \u201cAll Hazard\u201d sobre apoyo militar en emergencias y desastres.<\/p>\n\n\n\n<p>El Jefe del Departamento&nbsp;de&nbsp;Conducci\u00f3n Militar en Desastres de la Direcci\u00f3n Operaciones y Conducci\u00f3n Conjunta, Coronel Marcelo Montesinos De Ugarte particip\u00f3, junto a personal del Estado Mayor Conjunto, mediante la modalidad online, en un intercambio de experiencias con el Departamento Militar del Estado de Texas (TMD). Lo anterior, se efectu\u00f3 dentro del marco del programa de actividades bilaterales e intercambios vigentes entre Chile y Texas.<\/p>\n\n\n\n<p>En esta ocasi\u00f3n, los expertos en materia de emergencias y desastres militar del TMD y la U.S. Army South (ARSOUTH), junto con las componentes de los servicios locales de emergencia, efectuaron un resumen de las actividades de los apoyos realizados durante el a\u00f1o 2020 \u2013 2021, dando a conocer las actividades efectuadas durante la pandemia por COVID-19, Huracanes e invierno blanco que azot\u00f3 al Estado de Texas en febrero del presente a\u00f1o, exponiendo las experiencias y lecciones aprendidas obtenidas durante el apoyo c\u00edvico-militar realizado. Posteriormente, las diferentes componentes intercambiaron opiniones y realidades locales sobre los mejores procedimientos de apoyo, para enfrentar las diferentes variables de riesgos existentes en cada pa\u00eds, junto a las capacidades disponibles y log\u00edstica asociada.<\/p>\n\n\n\n<p>Las relaciones de amistad entre el EMCO y el TMD en el \u00e1mbito de la Defensa, constituyen una asociaci\u00f3n de cooperaci\u00f3n mutua que contribuye entre otras al fortalecimiento del \u00e1rea de misi\u00f3n de \u201cEmergencia Nacional y Protecci\u00f3n Civil\u201d, permitiendo un importante intercambio de experiencias, generando sinergia en el proceso de mejoras y acci\u00f3n eficiente y eficaz ante las emergencias.<\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/EMCO20210525-001-614x330.jpg\" alt=\"EMCO20210525-001\" class=\"wp-image-6075\"\/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 25 de mayo, el Estado Mayor Conjunto particip\u00f3 en un intercambio de experiencias con el Departamento Militar del Estado de Texas (TMD) de los Estados Unidos, consistente en un simulacro de ensayos de conceptos operacionales denominado \u201cAll Hazard\u201d sobre apoyo militar en emergencias y desastres. El Jefe del Departamento&nbsp;de&nbsp;Conducci\u00f3n Militar en Desastres de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[12,3],"tags":[],"class_list":["post-1714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1714"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1714\/revisions"}],"predecessor-version":[{"id":1715,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1714\/revisions\/1715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/1810"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}