{"id":1643,"date":"2021-06-04T09:21:00","date_gmt":"2021-06-04T13:21:00","guid":{"rendered":"http:\/\/10.195.30.25\/?p=1643"},"modified":"2021-09-27T15:46:00","modified_gmt":"2021-09-27T18:46:00","slug":"intercambio-de-experiencias-con-la-inspectoria-general-de-las-ff-aa-de-colombia","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2021\/06\/04\/intercambio-de-experiencias-con-la-inspectoria-general-de-las-ff-aa-de-colombia\/","title":{"rendered":"Intercambio de experiencias con la Inspector\u00eda General de las FF.AA. de Colombia"},"content":{"rendered":"\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/portada1-18-497x330.jpg\" alt=\"portada1\"\/><\/figure><\/div>\n\n\n\n<p>Este&nbsp;viernes 4 de junio, se ha iniciado un ciclo reuniones por video conferencias entre la Contralor\u00eda Interna del Estado Mayor Conjunto y el Inspector General de las Fuerzas Militares del Comando General de las Fuerzas Militares de Colombia (COGFM), Mayor General Juan Pablo Forero Tasc\u00f3n, con el objeto de intercambiar experiencias respecto de los mecanismos de Auditor\u00eda y Control Interno.<\/p>\n\n\n\n<p>Seg\u00fan lo acordado en la III Reuni\u00f3n Bilateral entre el Estado Mayor Conjunto y el Comando General de las Fuerzas Militares de Colombia, efectuado el a\u00f1o 2018, se ha iniciado un ciclo de reuniones por video conferencias dirigidas al aumento en la eficiencia, la gesti\u00f3n y adecuado empleo de los recursos p\u00fablicos. Durante el primer encuentro, se coordinaron las materias t\u00e9cnicas a tratar, la metodolog\u00eda y los puntos de la agenda respectiva.<\/p>\n\n\n\n<p>Dentro de los aspectos relevantes, est\u00e1n las experiencias y\/o beneficios adquiridos, en las labores de control interno relacionadas a las funciones y actividades propias de la fuerza operativa, y aquellas que se enfocan particularmente a la auditor\u00eda de procesos administrativos y financiero contables, con directrices y control externo del estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este&nbsp;viernes 4 de junio, se ha iniciado un ciclo reuniones por video conferencias entre la Contralor\u00eda Interna del Estado Mayor Conjunto y el Inspector General de las Fuerzas Militares del Comando General de las Fuerzas Militares de Colombia (COGFM), Mayor General Juan Pablo Forero Tasc\u00f3n, con el objeto de intercambiar experiencias respecto de los mecanismos&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[12,3],"tags":[],"class_list":["post-1643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1643"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1643\/revisions"}],"predecessor-version":[{"id":1646,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1643\/revisions\/1646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/1645"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}