{"id":14878,"date":"2026-03-17T15:27:38","date_gmt":"2026-03-17T18:27:38","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=14878"},"modified":"2026-03-17T16:21:23","modified_gmt":"2026-03-17T19:21:23","slug":"estado-mayor-conjunto-saluda-al-ministro-de-defensa-nacional-en-el-aniversario-207-del-ministerio","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2026\/03\/17\/estado-mayor-conjunto-saluda-al-ministro-de-defensa-nacional-en-el-aniversario-207-del-ministerio\/","title":{"rendered":"ESTADO MAYOR CONJUNTO SALUDA AL MINISTRO DE DEFENSA NACIONAL EN EL ANIVERSARIO 212 DEL MINISTERIO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14878\" class=\"elementor elementor-14878\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11f58953 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11f58953\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-304ccc0f\" data-id=\"304ccc0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7846bdea elementor-widget elementor-widget-text-editor\" data-id=\"7846bdea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>En el marco de la conmemoraci\u00f3n de los 212 a\u00f1os del Ministerio de Defensa Nacional, el Jefe del Estado Mayor Conjunto (JEMCO), General de Aviaci\u00f3n Leonardo Romanini Guti\u00e9rrez, encabez\u00f3 un saludo protocolar al Ministro de Defensa Nacional, Fernando Barros Tocornal.\u00a0 La instancia cont\u00f3 con la participaci\u00f3n del Subsecretario de Defensa, Rodrigo \u00c1lvarez Aguirre y del Subsecretario para las Fuerzas Armadas, Christian Bol\u00edvar Romero.<br \/><br \/>El General Romanini estuvo acompa\u00f1ado por el Subjefe del Estado Mayor Conjunto, Vicealmirante Juan Pablo Mar\u00edn Fern\u00e1ndez, y por el Director de Educaci\u00f3n, Doctrina y Entrenamiento Conjunto, General de Brigada Ricardo Duarte Machuca, quienes se sumaron a este gesto institucional.<\/p>\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-14878_9fcc61-04{margin:-2.5px;}.kb-gallery-type-masonry.kb-gallery-id-14878_9fcc61-04 .kadence-blocks-gallery-item{padding:2.5px;}.kb-gallery-id-14878_9fcc61-04 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-14878_9fcc61-04 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-14878_9fcc61-04 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-14878_9fcc61-04 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet2.jpg\" width=\"900\" height=\"601\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet2.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet2.jpg\" data-id=\"14881\" class=\"wp-image-14881\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet2.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet2-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet2-768x513.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet1.jpg\" width=\"900\" height=\"601\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet1.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet1.jpg\" data-id=\"14880\" class=\"wp-image-14880\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet1.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet1-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/03\/260317-saludo-JEMCO-MINDEF-aniver-intranet1-768x513.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En el marco de la conmemoraci\u00f3n de los 212 a\u00f1os del Ministerio de Defensa Nacional, el Jefe del Estado Mayor Conjunto (JEMCO), General de Aviaci\u00f3n Leonardo Romanini Guti\u00e9rrez, encabez\u00f3 un saludo protocolar al Ministro de Defensa Nacional, Fernando Barros Tocornal.\u00a0 La instancia cont\u00f3 con la participaci\u00f3n del Subsecretario de Defensa, Rodrigo \u00c1lvarez Aguirre y del&#8230;<\/p>\n","protected":false},"author":7,"featured_media":14883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[41,3],"tags":[],"class_list":["post-14878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-41","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=14878"}],"version-history":[{"count":5,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14878\/revisions"}],"predecessor-version":[{"id":14887,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14878\/revisions\/14887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/14883"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=14878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=14878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=14878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}