{"id":14703,"date":"2026-01-28T12:44:58","date_gmt":"2026-01-28T15:44:58","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=14703"},"modified":"2026-01-28T12:44:58","modified_gmt":"2026-01-28T15:44:58","slug":"cambio-de-mando-de-la-direccion-de-educacion-doctrina-y-entrenamiento-conjunto","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2026\/01\/28\/cambio-de-mando-de-la-direccion-de-educacion-doctrina-y-entrenamiento-conjunto\/","title":{"rendered":"CAMBIO DE MANDO DE LA DIRECCI\u00d3N DE EDUCACI\u00d3N, DOCTRINA Y ENTRENAMIENTO CONJUNTO"},"content":{"rendered":"\n<p><a>Este 28 de enero, en una actividad encabezada por el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Leonardo Romanini, se desarroll\u00f3 la entrega y firma de actas de la Direcci\u00f3n de Educaci\u00f3n, Doctrina y Entrenamiento Conjunto, instancia que cont\u00f3 con la presencia del Subjefe del Estado Mayor Conjunto, Vicealmirante\u00a0 Juan Pablo Mar\u00edn Fern\u00e1ndez, de los Directores del EMCO y de la dotaci\u00f3n de la DIREDENCO.<\/a><\/p>\n\n\n\n<p>En la ocasi\u00f3n, el Coronel Francisco Corval\u00e1n Espejo quien se desempe\u00f1aba como Director suplente de la DIREDENCO, hizo entrega del mando al General de Brigada Ricardo Duarte Machuca, quien anteriormente se desempe\u00f1\u00f3 como Jefe de la Misi\u00f3n Militar, Agregado de Defensa y Militar de la embajada de Chile en los Estados Unidos y Jefe de la Delegaci\u00f3n permanente de Chile ante la Junta Interamericana de Defensa.<\/p>\n\n\n\n<p>La <a> Direcci\u00f3n de Educaci\u00f3n, Doctrina y Entrenamiento Conjunto<\/a> es la encargada de dar cumplimiento al procedimiento de Educaci\u00f3n para capacitar al personal en las materias inherentes a la acci\u00f3n conjunta de las Fuerzas Armadas, as\u00ed como de formular, elaborar y mantener actualizada la doctrina conjunta y combinada para la planificaci\u00f3n, preparaci\u00f3n, ejecuci\u00f3n y evaluaci\u00f3n del empleo conjunto y conjunto combinado de la fuerza.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-14703_a732be-8f{overflow:hidden;}.kb-gallery-type-carousel.kb-gallery-id-14703_a732be-8f .kt-blocks-carousel .kt-blocks-carousel-init:not( .splide-initialized ){margin-left:-2px;margin-right:-2px;}.kb-gallery-type-carousel.kb-gallery-id-14703_a732be-8f .kt-blocks-carousel .kt-blocks-carousel-init:not( .splide-initialized ) .kb-slide-item{padding-left:2px;padding-right:2px;}.kb-gallery-id-14703_a732be-8f .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-14703_a732be-8f .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-14703_a732be-8f.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-14703_a732be-8f.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}<\/style><div class=\"kb-gallery-wrap-id-14703_a732be-8f alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-carousel kb-gallery-id-14703_a732be-8f kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div class=\"kt-blocks-carousel-init kb-gallery-carousel kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"2\" data-columns-xl=\"2\" data-columns-md=\"2\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"4px\" data-slider-gap-tablet=\"4px\" data-slider-gap-mobile=\"4px\" data-show-pause-button=\"false\" aria-label=\"Photo Gallery Carousel\"><li class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet2.jpg\" width=\"900\" height=\"602\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet2.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet2.jpg\" data-id=\"14705\" class=\"wp-image-14705 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet2.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet2-300x201.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet2-768x514.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet3.jpg\" width=\"900\" height=\"602\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet3.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet3.jpg\" data-id=\"14706\" class=\"wp-image-14706 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet3.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet3-300x201.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2026\/01\/20260128-Cambio-mando-DIREDENCO-intranet3-768x514.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Este 28 de enero, en una actividad encabezada por el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Leonardo Romanini, se desarroll\u00f3 la entrega y firma de actas de la Direcci\u00f3n de Educaci\u00f3n, Doctrina y Entrenamiento Conjunto, instancia que cont\u00f3 con la presencia del Subjefe del Estado Mayor Conjunto, Vicealmirante\u00a0 Juan Pablo Mar\u00edn Fern\u00e1ndez, de&#8230;<\/p>\n","protected":false},"author":5,"featured_media":14704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[41,3],"tags":[],"class_list":["post-14703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-41","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=14703"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14703\/revisions"}],"predecessor-version":[{"id":14707,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14703\/revisions\/14707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/14704"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=14703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=14703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=14703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}