{"id":14456,"date":"2025-11-25T10:00:00","date_gmt":"2025-11-25T13:00:00","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=14456"},"modified":"2025-11-26T09:20:03","modified_gmt":"2025-11-26T12:20:03","slug":"jefe-del-emco-expone-en-seminario-de-la-anepe","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2025\/11\/25\/jefe-del-emco-expone-en-seminario-de-la-anepe\/","title":{"rendered":"JEFE DEL EMCO EXPONE EN SEMINARIO DE LA ANEPE"},"content":{"rendered":"\n<p>Este 24 de noviembre en dependencias de la Academia Nacional de Estudios Pol\u00edticos y Estrat\u00e9gicos (ANEPE) se dio inicio al Seminario para Oficiales Generales y Almirantes de las Fuerzas Armadas reci\u00e9n ascendidos.<\/p>\n\n\n\n<p>La instancia, inaugurada por el Subsecretario de Defensa Ricardo Montero, cont\u00f3 con una intervenci\u00f3n del Jefe del Estado Mayor Conjunto General de Aviaci\u00f3n Leonardo Romanini quien present\u00f3 un an\u00e1lisis sobre la evoluci\u00f3n y desaf\u00edos de la Instituci\u00f3n.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que este seminario se realiza desde el 1999 y considera conferencias en materias de Defensa, Seguridad, Relaciones Internacionales, Transparencia, Probidad y Justicia, entre otros.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"600\" data-id=\"14458\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet-8.jpg\" alt=\"\" class=\"wp-image-14458\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet-8.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet-8-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet-8-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"900\" height=\"600\" data-id=\"14459\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet2-9.jpg\" alt=\"\" class=\"wp-image-14459\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet2-9.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet2-9-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet2-9-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"900\" height=\"600\" data-id=\"14460\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet4-8.jpg\" alt=\"\" class=\"wp-image-14460\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet4-8.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet4-8-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/11\/intranet4-8-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Este 24 de noviembre en dependencias de la Academia Nacional de Estudios Pol\u00edticos y Estrat\u00e9gicos (ANEPE) se dio inicio al Seminario para Oficiales Generales y Almirantes de las Fuerzas Armadas reci\u00e9n ascendidos. La instancia, inaugurada por el Subsecretario de Defensa Ricardo Montero, cont\u00f3 con una intervenci\u00f3n del Jefe del Estado Mayor Conjunto General de Aviaci\u00f3n&#8230;<\/p>\n","protected":false},"author":7,"featured_media":14457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[33,3],"tags":[],"class_list":["post-14456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-33","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=14456"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14456\/revisions"}],"predecessor-version":[{"id":14461,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/14456\/revisions\/14461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/14457"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=14456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=14456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=14456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}