{"id":13937,"date":"2025-10-10T08:58:05","date_gmt":"2025-10-10T11:58:05","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=13937"},"modified":"2025-10-13T13:04:38","modified_gmt":"2025-10-13T16:04:38","slug":"jefe-del-estado-mayor-conjunto-supervisa-desarrollo-del-ejercicio-solidaridad-2025-en-la-region-de-los-lagos","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2025\/10\/10\/jefe-del-estado-mayor-conjunto-supervisa-desarrollo-del-ejercicio-solidaridad-2025-en-la-region-de-los-lagos\/","title":{"rendered":"JEFE DEL ESTADO MAYOR CONJUNTO SUPERVISA DESARROLLO DEL EJERCICIO \u201cSOLIDARIDAD 2025\u201d EN LA REGI\u00d3N DE LOS LAGOS"},"content":{"rendered":"\n<p>Este 9 de octubre, el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Leonardo Romanini, se traslad\u00f3 hasta la Regi\u00f3n de Los Lagos para supervisar el desarrollo de los eventos programados durante el Ejercicio conjunto, binacional e interagencial \u201cSolidaridad 2025\u201d.<\/p>\n\n\n\n<p><br>Al iniciar la jornada, el General Romanini sostuvo una reuni\u00f3n con parte del personal de la Direcci\u00f3n del Ejercicio, donde se le expuso sobre los distintos eventos ejecutados desde el pasado 4 de octubre.<br>Posteriormente, junto al Director de Operaciones y Conducci\u00f3n Conjunta del EMCO, Contraalmirante \u00d3scar Manzano, y al Director de Planificaci\u00f3n Conjunta del EMCO, General de Brigada A\u00e9rea (A) Eduardo Cuadra, se traslad\u00f3 hasta la ciudad de Puerto Montt, donde presenci\u00f3 desde la Costanera un operativo de b\u00fasqueda y rescate de una persona desaparecida en el mar.<\/p>\n\n\n\n<p><br>Asimismo, revist\u00f3 el desarrollo de los eventos de potabilizaci\u00f3n de agua, as\u00ed como de derrame y contenci\u00f3n de hidrocarburos y rescate de persona desaparecida en el lago.<\/p>\n\n\n\n<p><br>Cabe se\u00f1alar que durante la jornada se efectu\u00f3 la evacuaci\u00f3n del edificio consistorial de la Municipalidad de Puerto Varas y un operativo de rescate en un incendio estructural, instancias en las que participaron de manera coordinada las Fuerzas Armadas y las instituciones civiles.<\/p>\n\n\n\n<p><br>El Director de Operaciones del Ejercicio Solidaridad 2025, Coronel Carlos Cammas, destac\u00f3 el desempe\u00f1o del personal participante, se\u00f1alando que:<br>\u201cEl resultado ha sido positivo, hemos cumplido con los objetivos esperados para el desarrollo de los eventos. Sin duda, la presencia y actuaci\u00f3n de los integrantes del Ejercicio ha sido brillante. Hemos visto el despliegue de capacidades y se ha logrado demostrar el trabajo conjunto, combinado e interagencial, orientado a resguardar y proteger la vida de las personas ante una emergencia\u201d.<\/p>\n\n\n\n<p><br>El Ejercicio Solidaridad 2025, dirigido por el Estado Mayor Conjunto, organismo t\u00e9cnico dependiente del Ministerio de Defensa Nacional, tiene por objetivo evaluar la capacidad de respuesta frente a cat\u00e1strofes naturales y validar en terreno la integraci\u00f3n entre instituciones militares y civiles.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-13937_bc8b87-63{margin:-5px;}.kb-gallery-type-masonry.kb-gallery-id-13937_bc8b87-63 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-13937_bc8b87-63 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-13937_bc8b87-63 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-13937_bc8b87-63 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-13937_bc8b87-63 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna01.jpg\" width=\"900\" height=\"599\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna01.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna01.jpg\" data-id=\"13960\" class=\"wp-image-13960\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna01.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna01-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna01-768x511.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna02.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna02.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna02.jpg\" data-id=\"13961\" class=\"wp-image-13961\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna02.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna02-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna02-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna03.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna03.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna03.jpg\" data-id=\"13962\" class=\"wp-image-13962\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna03.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna03-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna03-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna04.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna04.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna04.jpg\" data-id=\"13963\" class=\"wp-image-13963\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna04.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna04-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna04-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna05.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna05.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna05.jpg\" data-id=\"13964\" class=\"wp-image-13964\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna05.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna05-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna05-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna06.jpg\" width=\"900\" height=\"599\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna06.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna06.jpg\" data-id=\"13965\" class=\"wp-image-13965\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna06.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna06-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna06-768x511.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna07.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna07.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna07.jpg\" data-id=\"13966\" class=\"wp-image-13966\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna07.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna07-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna07-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna08.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna08.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna08.jpg\" data-id=\"13967\" class=\"wp-image-13967\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna08.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna08-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna08-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna09.jpg\" width=\"900\" height=\"599\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna09.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna09.jpg\" data-id=\"13968\" class=\"wp-image-13968\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna09.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna09-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna09-768x511.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna10.jpg\" width=\"900\" height=\"602\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna10.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna10.jpg\" data-id=\"13969\" class=\"wp-image-13969\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna10.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna10-300x201.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna10-768x514.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna11.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna11.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna11.jpg\" data-id=\"13970\" class=\"wp-image-13970\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna11.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna11-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna11-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna12.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna12.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna12.jpg\" data-id=\"13971\" class=\"wp-image-13971\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna12.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna12-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna12-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna13.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna13.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna13.jpg\" data-id=\"13972\" class=\"wp-image-13972\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna13.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna13-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna13-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna14.jpg\" width=\"900\" height=\"599\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna14.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna14.jpg\" data-id=\"13973\" class=\"wp-image-13973\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna14.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna14-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna14-768x511.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna15.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna15.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna15.jpg\" data-id=\"13974\" class=\"wp-image-13974\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna15.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna15-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna15-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna16.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna16.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna16.jpg\" data-id=\"13975\" class=\"wp-image-13975\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna16.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna16-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna16-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna17.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna17.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna17.jpg\" data-id=\"13976\" class=\"wp-image-13976\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna17.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna17-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna17-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna18.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna18.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna18.jpg\" data-id=\"13977\" class=\"wp-image-13977\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna18.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna18-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna18-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna19.jpg\" width=\"900\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna19.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna19.jpg\" data-id=\"13978\" class=\"wp-image-13978\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna19.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna19-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna19-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:900px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:67%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna20.jpg\" width=\"900\" height=\"603\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna20.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna20.jpg\" data-id=\"13979\" class=\"wp-image-13979\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna20.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna20-300x201.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna20-768x515.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:901px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:66%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna21.jpg\" width=\"901\" height=\"600\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna21.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna21.jpg\" data-id=\"13980\" class=\"wp-image-13980\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna21.jpg 901w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna21-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/10\/20251009-interna21-768x511.jpg 768w\" sizes=\"(max-width: 901px) 100vw, 901px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Este 9 de octubre, el Jefe del Estado Mayor Conjunto, General de Aviaci\u00f3n Leonardo Romanini, se traslad\u00f3 hasta la Regi\u00f3n de Los Lagos para supervisar el desarrollo de los eventos programados durante el Ejercicio conjunto, binacional e interagencial \u201cSolidaridad 2025\u201d. Al iniciar la jornada, el General Romanini sostuvo una reuni\u00f3n con parte del personal de&#8230;<\/p>\n","protected":false},"author":5,"featured_media":13938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[33,3,36],"tags":[],"class_list":["post-13937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-33","category-noticias","category-solidaridad"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/13937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=13937"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/13937\/revisions"}],"predecessor-version":[{"id":13981,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/13937\/revisions\/13981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/13938"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=13937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=13937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=13937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}