{"id":1391,"date":"2021-09-03T16:28:00","date_gmt":"2021-09-03T20:28:00","guid":{"rendered":"http:\/\/10.195.30.25\/?p=1391"},"modified":"2022-07-06T16:23:02","modified_gmt":"2022-07-06T20:23:02","slug":"izamiento-de-la-gran-bandera-nacional-en-el-mes-de-las-glorias-del-ejercito","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2021\/09\/03\/izamiento-de-la-gran-bandera-nacional-en-el-mes-de-las-glorias-del-ejercito\/","title":{"rendered":"Izamiento de la Gran Bandera Nacional en el mes de las Glorias del Ej\u00e9rcito"},"content":{"rendered":"\n<p>Este viernes 3 de septiembre, y luego de 18 meses sin realizarse este acto producto de los protocolos COVID-19, se efectu\u00f3 la ceremonia de izamiento de la Gran Bandera Bicentenario en la Plaza de la Ciudadan\u00eda con ocasi\u00f3n de las Glorias del Ej\u00e9rcito de Chile.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"620\" height=\"286\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-1.jpg\" alt=\"\" class=\"wp-image-9180\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-1.jpg 620w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-1-300x138.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-1-350x161.jpg 350w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/figure>\n<\/div>\n\n\n<p>La actividad fue presidida por el Ministro de Defensa Nacional Baldo Prokurika y cont\u00f3 con la presencia del Comandante en Jefe del Ej\u00e9rcito, Ricardo Mart\u00ednez Menanteau, el Jefe del Estado Mayor Conjunto, General de Divisi\u00f3n Javier Iturriaga del Campo, el Subsecretario de Defensa, Subsecretario para las Fuerzas Armadas, autoridades del alto mando del Ej\u00e9rcito y oficiales en retiro.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"620\" height=\"330\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/portada-web-2.jpg\" alt=\"\" class=\"wp-image-9181\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/portada-web-2.jpg 620w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/portada-web-2-300x160.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/portada-web-2-350x186.jpg 350w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/figure>\n<\/div>\n\n\n<p>El izamiento estuvo a cargo de efectivos de la Escuela Militar y Escuela de Suboficiales, personal de la salud y de las distintas especialidades de la Instituci\u00f3n, junto con las unidades hist\u00f3ricas del Regimiento de Infanter\u00eda N\u00b01 \u201cBuin\u201d, Regimiento de Artiller\u00eda N\u00b01 \u201cTacna\u201d, Escuela de Infanter\u00eda y el destacamento de honor integrado por un escuadr\u00f3n del Regimiento Escolta Presidencial N\u00b01 \u201cGranaderos\u201d.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"620\" height=\"287\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-3.jpg\" alt=\"\" class=\"wp-image-9182\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-3.jpg 620w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-3-300x139.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-3-350x162.jpg 350w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/figure>\n<\/div>\n\n\n<p>Al final de la ceremonia se vivi\u00f3 un emotivo momento cuando una trompeta de la banda instrumental realiz\u00f3 un toque de silencio en homenaje a los 37 mil compatriotas fallecidos producto de la pandemia.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"287\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-2.jpg\" alt=\"\" class=\"wp-image-9183\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-2.jpg 620w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-2-300x139.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2022\/07\/interna-web-2-350x162.jpg 350w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Este viernes 3 de septiembre, y luego de 18 meses sin realizarse este acto producto de los protocolos COVID-19, se efectu\u00f3 la ceremonia de izamiento de la Gran Bandera Bicentenario en la Plaza de la Ciudadan\u00eda con ocasi\u00f3n de las Glorias del Ej\u00e9rcito de Chile. La actividad fue presidida por el Ministro de Defensa Nacional&#8230;<\/p>\n","protected":false},"author":4,"featured_media":1695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[12,3],"tags":[],"class_list":["post-1391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=1391"}],"version-history":[{"count":2,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1391\/revisions"}],"predecessor-version":[{"id":9184,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/1391\/revisions\/9184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/1695"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=1391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=1391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=1391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}