{"id":13097,"date":"2025-07-22T15:10:11","date_gmt":"2025-07-22T19:10:11","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=13097"},"modified":"2025-07-22T15:10:11","modified_gmt":"2025-07-22T19:10:11","slug":"cecopac-prepara-a-contingente-chileno-previo-a-despliegue-a-mision-de-paz-en-chipre","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2025\/07\/22\/cecopac-prepara-a-contingente-chileno-previo-a-despliegue-a-mision-de-paz-en-chipre\/","title":{"rendered":"CECOPAC PREPARA A CONTINGENTE CHILENO PREVIO A DESPLIEGUE A MISI\u00d3N DE PAZ EN CHIPRE"},"content":{"rendered":"\n<p>En el marco del per\u00edodo de pre despliegue del contingente que ser\u00e1 desplegado a la Fuerza de las Naciones Unidas para el Mantenimiento de la Paz en Chipre, el Centro Conjunto para Operaciones de Paz de Chile llev\u00f3 a cabo el per\u00edodo de pre despliegue te\u00f3rico y pr\u00e1ctico a personal del Ej\u00e9rcito de Chile que integra la comisi\u00f3n.<\/p>\n\n\n\n<p>Durante el mes de junio y julio, se le entreg\u00f3 al contingente el conocimiento que le permitir\u00e1 desenvolverse en el \u00e1rea de misi\u00f3n, desarrollando las competencias necesarias para el cumplimiento de tareas y funciones que ejecutar\u00e1n como parte de la Fuerza de Tarea Argentina en Chipre.<\/p>\n\n\n\n<p>La fase pr\u00e1ctica, que se efectu\u00f3 en el Campo de entrenamiento de la Infanter\u00eda de Marina de la Armada en el Fuerte Aguayo, el contingente que ser\u00e1 desplegado a partir del mes de agosto, puso a prueba sus conocimientos te\u00f3ricos adem\u00e1s de recibir capacitaciones entorno a las actividades de patrullajes, reportes, observaci\u00f3n, adem\u00e1s de llevar a cabo ejercicios simulados con situaciones ficticias que podr\u00edan ocurrir en el \u00e1rea de misi\u00f3n.<\/p>\n\n\n\n<p>En ese sentido, el Teniente Primero IM Crist\u00f3bal L\u00f3pez, Jefe de Curso UNFICYP45 se\u00f1al\u00f3 que \u201c<em>durante estas dos semanas de instrucci\u00f3n, 8 alumnos participaron en un exigente proceso formativo, que incluy\u00f3 una etapa te\u00f3rica, centrada en el Core Pre-deployment Training Material (CPTM) y contenidos espec\u00edficos de la misi\u00f3n, adem\u00e1s de una fase pr\u00e1ctica, orientada al desarrollo de habilidades a trav\u00e9s de simulaciones que reproducen escenarios reales del terreno<\/em>\u201d.<\/p>\n\n\n\n<p>Agreg\u00f3, adem\u00e1s que \u201c<em>este curso busc\u00f3 fortalecer las competencias necesarias para enfrentar los desaf\u00edos del mandato con eficacia, disciplina y apego a los principios que rigen las operaciones de mantenimiento de la paz de Naciones Unidas<\/em>.\u201d<\/p>\n\n\n\n<p>Establecido por el Consejo de Seguridad, la UNFICYP se ha mantenido activa desde 1964 con el prop\u00f3sito de impedir nuevos enfrentamientos entre las comunidades grecochipriota y turcochipriota. Actualmente son 10 los pa\u00edses que contribuyen con un contingente en Chipre, entre ellos Chile (desde el a\u00f1o 1999), con militares que integran la \u201cFuerza de Tarea Argentina\u201d durante un per\u00edodo de seis meses, altern\u00e1ndose entre el Ej\u00e9rcito y la Armada.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"603\" data-id=\"13099\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet-2.jpg\" alt=\"\" class=\"wp-image-13099\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet-2.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet-2-300x201.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet-2-768x515.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"900\" height=\"600\" data-id=\"13101\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet2-7.jpg\" alt=\"\" class=\"wp-image-13101\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet2-7.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet2-7-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet2-7-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"900\" height=\"623\" data-id=\"13100\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet3-7.jpg\" alt=\"\" class=\"wp-image-13100\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet3-7.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet3-7-300x208.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/07\/intranet3-7-768x532.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del per\u00edodo de pre despliegue del contingente que ser\u00e1 desplegado a la Fuerza de las Naciones Unidas para el Mantenimiento de la Paz en Chipre, el Centro Conjunto para Operaciones de Paz de Chile llev\u00f3 a cabo el per\u00edodo de pre despliegue te\u00f3rico y pr\u00e1ctico a personal del Ej\u00e9rcito de Chile que&#8230;<\/p>\n","protected":false},"author":7,"featured_media":13098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[33,3],"tags":[],"class_list":["post-13097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-33","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/13097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=13097"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/13097\/revisions"}],"predecessor-version":[{"id":13102,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/13097\/revisions\/13102"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/13098"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=13097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=13097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=13097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}