{"id":12701,"date":"2025-04-30T09:19:31","date_gmt":"2025-04-30T13:19:31","guid":{"rendered":"https:\/\/www.emco.mil.cl\/?p=12701"},"modified":"2025-04-30T09:19:31","modified_gmt":"2025-04-30T13:19:31","slug":"contingente-desplegado-a-bosnia-y-herzegovina-realizo-saludo-protocolar-a-jefe-del-emco","status":"publish","type":"post","link":"https:\/\/www.emco.mil.cl\/index.php\/2025\/04\/30\/contingente-desplegado-a-bosnia-y-herzegovina-realizo-saludo-protocolar-a-jefe-del-emco\/","title":{"rendered":"CONTINGENTE DESPLEGADO A BOSNIA Y HERZEGOVINA REALIZ\u00d3 SALUDO PROTOCOLAR A JEFE DEL EMCO"},"content":{"rendered":"\n<p>Este 28 de abril, el Jefe del Estado Mayor Conjunto Vicealmirante Pablo Niemann junto al Director de Operaciones y Conducci\u00f3n Conjunta del EMCO, Contraalmirante \u00d3scar Manzano, despidi\u00f3 al personal que ser\u00e1 desplegado a la Operaci\u00f3n de Paz EUFOR ALTHEA en Bosnia y Herzegovina.<\/p>\n\n\n\n<p>Durante los pr\u00f3ximos ocho meses, el contingente integrado por personal del Ej\u00e9rcito de Chile y de la Armada cumplir\u00e1 funciones en el Cuartel General de Camp Butmir, ubicado en Sarajevo, capital de Bosnia-Herzegovina, siendo el personal chileno la Fuerza de Paz n\u00famero 41 (CHILFOR 41) en cumplir misiones en el pa\u00eds balc\u00e1nico.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"602\" data-id=\"12703\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET1-6.jpg\" alt=\"\" class=\"wp-image-12703\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET1-6.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET1-6-300x201.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET1-6-768x514.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"900\" height=\"602\" data-id=\"12704\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET2-7.jpg\" alt=\"\" class=\"wp-image-12704\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET2-7.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET2-7-300x201.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET2-7-768x514.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"900\" height=\"605\" data-id=\"12706\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET3-2.jpg\" alt=\"\" class=\"wp-image-12706\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET3-2.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET3-2-300x202.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANET3-2-768x516.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" data-id=\"12705\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANETportada.jpg\" alt=\"\" class=\"wp-image-12705\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANETportada.jpg 900w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANETportada-300x200.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2025\/04\/INTRANETportada-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Este 28 de abril, el Jefe del Estado Mayor Conjunto Vicealmirante Pablo Niemann junto al Director de Operaciones y Conducci\u00f3n Conjunta del EMCO, Contraalmirante \u00d3scar Manzano, despidi\u00f3 al personal que ser\u00e1 desplegado a la Operaci\u00f3n de Paz EUFOR ALTHEA en Bosnia y Herzegovina. Durante los pr\u00f3ximos ocho meses, el contingente integrado por personal del Ej\u00e9rcito&#8230;<\/p>\n","protected":false},"author":7,"featured_media":12702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[33,3],"tags":[],"class_list":["post-12701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-33","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/12701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=12701"}],"version-history":[{"count":1,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/12701\/revisions"}],"predecessor-version":[{"id":12707,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/posts\/12701\/revisions\/12707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media\/12702"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=12701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/categories?post=12701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/tags?post=12701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}