{"id":555,"date":"2021-09-01T16:22:17","date_gmt":"2021-09-01T20:22:17","guid":{"rendered":"http:\/\/10.195.30.25\/?page_id=555"},"modified":"2021-10-20T14:21:04","modified_gmt":"2021-10-20T17:21:04","slug":"direccion-de-apoyo-general","status":"publish","type":"page","link":"https:\/\/www.emco.mil.cl\/index.php\/direccion-de-apoyo-general\/","title":{"rendered":"DIRECCI\u00d3N DE APOYO GENERAL"},"content":{"rendered":"<style>#kt-layout-id_3b259b-52 > .kt-row-column-wrap{align-content:start;}:where(#kt-layout-id_3b259b-52 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}#kt-layout-id_3b259b-52 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var( --global-kb-row-default-top, 25px );padding-bottom:var( --global-kb-row-default-bottom, 25px );padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(10% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(80% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)))minmax(0, calc(10% - ((var(--global-kb-gap-md, 2rem) * 2 )\/3)));}#kt-layout-id_3b259b-52 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){#kt-layout-id_3b259b-52 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){#kt-layout-id_3b259b-52 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){#kt-layout-id_3b259b-52 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}#kt-layout-id_3b259b-52 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style>\n<div class=\"wp-block-kadence-rowlayout alignnone\"><div id=\"kt-layout-id_3b259b-52\" class=\"kt-row-layout-inner kt-layout-id_3b259b-52\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-gutter-default kt-v-gutter-default kt-row-valign-top kt-row-layout-center-half kt-tab-layout-inherit kt-m-colapse-left-to-right kt-mobile-layout-row  kt-custom-first-width-10  kt-custom-second-width-80  kt-custom-third-width-10\"><style>.kadence-column_665fc3-0e > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_665fc3-0e > .kt-inside-inner-col,.kadence-column_665fc3-0e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_665fc3-0e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_665fc3-0e > .kt-inside-inner-col{flex-direction:column;}.kadence-column_665fc3-0e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_665fc3-0e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_665fc3-0e{position:relative;}@media all and (max-width: 1024px){.kadence-column_665fc3-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_665fc3-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-1 kadence-column_665fc3-0e\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n\n<style>.kadence-column_68c1bf-7d > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_68c1bf-7d > .kt-inside-inner-col,.kadence-column_68c1bf-7d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_68c1bf-7d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_68c1bf-7d > .kt-inside-inner-col{flex-direction:column;}.kadence-column_68c1bf-7d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_68c1bf-7d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_68c1bf-7d{position:relative;}@media all and (max-width: 1024px){.kadence-column_68c1bf-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_68c1bf-7d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-2 kadence-column_68c1bf-7d\"><div class=\"kt-inside-inner-col\">\n<p>\u00d3rgano encargado de generar y proporcionar el apoyo administrativo, log\u00edstico al Estado Mayor Conjunto, desarrollando las acciones y tareas necesarias para su cumplimiento. Otorgar seguridad y protecci\u00f3n a las instalaciones del Ministerio de Defensa Nacional y dependencias del Estado Mayor Conjunto, a trav\u00e9s de la Compa\u00f1\u00eda de Guardia del MDN.<\/p>\n\n\n<style>.kb-gallery-id-_464353-44 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-_464353-44 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-wrap-id-_464353-44.wp-block-kadence-advancedgallery{overflow:visible;}.kb-gallery-wrap-id-_464353-44.wp-block-kadence-advancedgallery .kt-blocks-carousel{overflow:visible;}<\/style>\n<div class=\"wp-block-kadence-advancedgallery kb-gallery-wrap-id-_464353-44\"><div class=\"kb-gallery-ul kb-gallery-type-slider kb-gallery-id-_464353-44 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div class=\"kt-blocks-carousel-init kb-blocks-slider kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"250\" data-slider-type=\"slider\" data-slider-scroll=\"1\" data-slider-arrows=\"true\" data-slider-dots=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\" data-slider-speed=\"3770\"><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land21\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land21\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Cia-de-Guardia-2020.jpg\" width=\"1024\" height=\"488\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Cia-de-Guardia-2020.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Cia-de-Guardia-2020.jpg\" data-id=\"7575\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/direccion-de-apoyo-general\/web-cia-de-guardia-2020\/\" class=\"wp-image-7575 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Cia-de-Guardia-2020.jpg 1024w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Cia-de-Guardia-2020-300x143.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Cia-de-Guardia-2020-768x366.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Cia-de-Guardia-2020-350x167.jpg 350w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land21\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land21\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Enfermeria-2020.jpg\" width=\"1024\" height=\"488\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Enfermeria-2020.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Enfermeria-2020.jpg\" data-id=\"7576\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/direccion-de-apoyo-general\/web-enfermeria-2020\/\" class=\"wp-image-7576 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Enfermeria-2020.jpg 1024w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Enfermeria-2020-300x143.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Enfermeria-2020-768x366.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Enfermeria-2020-350x167.jpg 350w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land21\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land21\"><img decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Transporte-Solidaridad-2014.jpg\" width=\"1024\" height=\"488\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Transporte-Solidaridad-2014.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Transporte-Solidaridad-2014.jpg\" data-id=\"7577\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/direccion-de-apoyo-general\/web-transporte-solidaridad-2014\/\" class=\"wp-image-7577 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Transporte-Solidaridad-2014.jpg 1024w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Transporte-Solidaridad-2014-300x143.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Transporte-Solidaridad-2014-768x366.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/web-Transporte-Solidaridad-2014-350x167.jpg 350w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><div class=\"kb-slide-item kb-gallery-slide-item\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption kb-has-image-ratio-land21\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land21\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/dag.jpg\" width=\"1024\" height=\"488\" alt=\"\" data-full-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/dag.jpg\" data-light-image=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/dag.jpg\" data-id=\"7571\" data-link=\"https:\/\/www.emco.mil.cl\/index.php\/direccion-de-apoyo-general\/dag-2\/\" class=\"wp-image-7571 skip-lazy\" srcset=\"https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/dag.jpg 1024w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/dag-300x143.jpg 300w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/dag-768x366.jpg 768w, https:\/\/www.emco.mil.cl\/wp-content\/uploads\/2021\/10\/dag-350x167.jpg 350w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column_dcd0bf-22 > .kt-inside-inner-col{border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;}.kadence-column_dcd0bf-22 > .kt-inside-inner-col,.kadence-column_dcd0bf-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_dcd0bf-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_dcd0bf-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column_dcd0bf-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column_dcd0bf-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_dcd0bf-22{position:relative;}@media all and (max-width: 1024px){.kadence-column_dcd0bf-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column_dcd0bf-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column inner-column-3 kadence-column_dcd0bf-22\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00d3rgano encargado de generar y proporcionar el apoyo administrativo, log\u00edstico al Estado Mayor Conjunto, desarrollando las acciones y tareas necesarias para su cumplimiento. Otorgar seguridad y protecci\u00f3n a las instalaciones del Ministerio de Defensa Nacional y dependencias del Estado Mayor Conjunto, a trav\u00e9s de la Compa\u00f1\u00eda de Guardia del MDN.<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-555","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/pages\/555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/comments?post=555"}],"version-history":[{"count":5,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/pages\/555\/revisions"}],"predecessor-version":[{"id":7930,"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/pages\/555\/revisions\/7930"}],"wp:attachment":[{"href":"https:\/\/www.emco.mil.cl\/index.php\/wp-json\/wp\/v2\/media?parent=555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}